{"id":10543,"date":"2021-06-24T10:00:00","date_gmt":"2021-06-24T08:00:00","guid":{"rendered":"https:\/\/www.host-fusion.com\/blog\/?p=10543"},"modified":"2021-06-17T11:25:01","modified_gmt":"2021-06-17T09:25:01","slug":"que-es-una-landing-page","status":"publish","type":"post","link":"https:\/\/www.host-fusion.com\/blog\/2021\/06\/24\/que-es-una-landing-page\/","title":{"rendered":"\u00bfQu\u00e9 es una landing page? Empieza a obtener conversiones"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"824\" height=\"243\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/landing-page.jpg\" alt=\"Qu\u00e9 es una landing page\" class=\"wp-image-10545\" title=\"Qu\u00e9 es una landing page\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/landing-page.jpg 824w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/landing-page-300x88.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/landing-page-768x226.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/landing-page-705x208.jpg 705w\" sizes=\"(max-width: 824px) 100vw, 824px\" \/><\/figure>\n\n\n\n<p>Una landing page sigue siendo una estupenda herramienta que ofrece toda una serie de posibilidades extra a cualquier proyecto web.<\/p>\n\n\n\n<p>Entre todas las estrategias de marketing digital, el <strong>dise\u00f1o de una landing page<\/strong> es una opci\u00f3n muy interesante, y una buena herramienta que sirve para llevar adelante acciones que se pueden complementar a su vez con otras relacionadas con campa\u00f1as publicitarias o email marketing.<\/p>\n\n\n\n<p>En este post te vamos a mostrar <strong>qu\u00e9 es una landing page<\/strong> y cu\u00e1les son todos esos aspectos clave que debes tener en cuenta a la hora de dise\u00f1arla para cualquier tipo de estrategia de marketing digital que quieras poner en marcha.<\/p>\n\n\n\n<p>\u00bfNos acompa\u00f1as?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es una Landing Page?<\/h2>\n\n\n\n<p>Podr\u00edamos traducirla como p\u00e1gina de aterrizaje, y adem\u00e1s creemos que en espa\u00f1ol es bastante significativo su significado pues explica de forma bastante simple y directa de que se trata.<\/p>\n\n\n\n<p>Una landing page es:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La p\u00e1gina de destino a la que se env\u00eda a un determinado p\u00fablico objetivo que previamente hemos captado en otro canal, su finalidad es convertir esas visitas en leads.<\/p><\/blockquote>\n\n\n\n<p>La forma de captar y atraer a ese posible cliente a este tipo de p\u00e1gina puede ser simplemente <strong>tras hacer clic en un anuncio o en una llamada a la acci\u00f3n<\/strong> que hayamos propuesto.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Te puede interesar: <a href=\"https:\/\/www.host-fusion.com\/blog\/2021\/03\/24\/que-es-marketing-de-contenidos\/\">\u00bfConoces qu\u00e9 es el Marketing de Contenidos y todas la ventajas que ofrece a tu marca?<\/a><\/em><\/p><\/blockquote>\n\n\n\n<p>Una p\u00e1gina de aterrizaje es una buena forma de enfocarnos en ofrecer a un posible cliente final todo el contenido necesario para que se decida a dejarnos el lead que perseguimos como objetivo.<\/p>\n\n\n\n<p>Por ejemplo, en el caso de que el lead sea la captaci\u00f3n de un email de suscripci\u00f3n para nuestra newsletter a lo largo de nuestra landing incluiremos contenido c\u00f3mo:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Por qu\u00e9 queremos que se suscriba<\/li><li>Qu\u00e9 le ofrecemos por suscribirse (podemos por ejemplo ofrecer un lead magnet)<\/li><li>Formulario de suscripci\u00f3n para que nos deje sus datos (nombre y email)<\/li><\/ul>\n\n\n\n<p>Como consecuencia de todo esto podemos afirmar que <strong>una buena Landing Page es la que consigue conversiones.<\/strong><\/p>\n\n\n\n<p>Por supuesto, para convertir, el dise\u00f1o de esta landing debe estar perfectamente realizado y orientado a la conversi\u00f3n final en la propia p\u00e1gina.<\/p>\n\n\n\n<p>Esa conversi\u00f3n final est\u00e1 totalmente <strong>ligada a los objetivos de la estrategia<\/strong> que nos hayamos marcado y dependiendo de estos podemos adaptarla a diferentes usos.<\/p>\n\n\n\n<p>Quiz\u00e1s para conocer mejor lo que define a este tipo de p\u00e1ginas de aterrizaje conviene tambi\u00e9n saber <strong>qu\u00e9 no es una landing page<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>No es la p\u00e1gina de inicio de tu web<\/li><li>No es la p\u00e1gina de servicio o producto habitual de tu web<\/li><li>No es una p\u00e1gina en la que no estemos pidiendo al usuario ninguna acci\u00f3n por su parte que podamos interpretar como un lead<\/li><li>No es una p\u00e1gina que no tenga un objetivo definido, claro y conciso<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.host-fusion.com\/hosting-para-woocommerce\/\"><img decoding=\"async\" width=\"824\" height=\"243\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/02\/elmejorhostingwoocommerce-1.jpg\" alt=\"El mejor Hosting para WooCommerce\" class=\"wp-image-9796\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/02\/elmejorhostingwoocommerce-1.jpg 824w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/02\/elmejorhostingwoocommerce-1-300x88.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/02\/elmejorhostingwoocommerce-1-768x226.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/02\/elmejorhostingwoocommerce-1-705x208.jpg 705w\" sizes=\"(max-width: 824px) 100vw, 824px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Ventajas de implementar una Landing Page<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Mayor rentabilidad<\/h3>\n\n\n\n<p>Su dise\u00f1o e implementaci\u00f3n tiene <strong>menos costes<\/strong> que montar una web completa, adem\u00e1s est\u00e1 m\u00e1s enfocada en un objetivo concreto por lo que su optimizaci\u00f3n para la conversi\u00f3n por lo general tiende a ser mayor que en un site.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Formato que puede ser utilizado para diferentes campa\u00f1as<\/h3>\n\n\n\n<p>Dise\u00f1ar una p\u00e1gina as\u00ed puede ser interesante si con cierta frecuencia lanzamos campa\u00f1as similares ya que nos permite adaptar de forma r\u00e1pida y sencilla su dise\u00f1o al tipo de campa\u00f1a que estemos lanzando.<\/p>\n\n\n\n<p>Por ejemplo, en el caso de la creaci\u00f3n de una p\u00e1gina para la campa\u00f1a promocional de un producto o servicio de nuestra marca.<\/p>\n\n\n\n<p>Si los productos o servicios son similares bastar\u00e1 con <strong>cambiar algunos textos e im\u00e1genes<\/strong> solamente para adaptar por completo esa p\u00e1gina a cada campa\u00f1a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mejor experiencia para el usuario<\/h3>\n\n\n\n<p>Una correcta optimizaci\u00f3n de esta p\u00e1gina contendr\u00e1 todo el contenido que realmente interese a nuestros usuarios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Medir y analizar mucho mejor su \u00e9xito<\/h3>\n\n\n\n<p>Al tratarse de una \u00fanica p\u00e1gina con secciones, elementos y comportamientos del usuario muy definidos es mucho <strong>m\u00e1s sencillo medir y analizar<\/strong>, no s\u00f3lo las conversiones sino tambi\u00e9n las posibles mejoras a aplicar en todo momento de forma m\u00e1s sencilla que una web completa. No s\u00f3lo eso, los datos y m\u00e9tricas que obtenemos tan resultan de mucho valor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La anatom\u00eda de una landing perfecta<\/h2>\n\n\n\n<p>A continuaci\u00f3n te vamos a mostrar los elementos clave de los que debe disponer una buena p\u00e1gina de aterrizaje.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Encabezado<\/h3>\n\n\n\n<p>El encabezado o \u00abheader\u00bb es la parte m\u00e1s visible de toda la p\u00e1gina y a diferencia de otras p\u00e1ginas de una web en este caso su dise\u00f1o es ligeramente diferente.<\/p>\n\n\n\n<p>Si en una web esta parte de la p\u00e1gina sirve para colocar enlaces a las p\u00e1ginas m\u00e1s interesantes de nuestra web en este caso no nos interesa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"858\" height=\"475\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/vodafone-header.jpg\" alt=\"Landing page Vodafone\" class=\"wp-image-10546\" title=\"Landing page Vodafone\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/vodafone-header.jpg 858w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/vodafone-header-300x166.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/vodafone-header-768x425.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/vodafone-header-705x390.jpg 705w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure>\n\n\n\n<p>En esta landing de oferta de Vodafone han creado un men\u00fa superior que sirve para mostrar diferentes planes en la misma p\u00e1gina pero que en ning\u00fan caso redirigen a la web principal.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>S\u00f3lo debemos poner enlaces partes de esta misma p\u00e1gina o de la propia llamada a la acci\u00f3n.<\/p><\/blockquote>\n\n\n\n<p>En este apartado el texto que empleamos es el <strong>t\u00edtulo<\/strong>, este es el m\u00e1s relevante de todos y debe adem\u00e1s de ir acompa\u00f1ado de un subt\u00edtulo que ampl\u00eda el mensaje y lo refuerza.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"858\" height=\"338\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/mailchimp.jpg\" alt=\"landing page mailchimp\" class=\"wp-image-10547\" title=\"landing page mailchimp\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/mailchimp.jpg 858w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/mailchimp-300x118.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/mailchimp-768x303.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/mailchimp-705x278.jpg 705w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure>\n\n\n\n<p>La anterior captura es la p\u00e1gina de aterrizaje de mailchimp vinculada a su campa\u00f1a de publicidad con Google Ads.<\/p>\n\n\n\n<p>Es un buen ejemplo de c\u00f3mo redactar un t\u00edtulo y subt\u00edtulo dejando claro <strong>qu\u00e9 puede ofrecer su herramienta a los clientes.<\/strong><\/p>\n\n\n\n<p>Este texto ha de ser visualizado por el usuario que aterriza <strong>sin necesidad de hacer scroll<\/strong> y adem\u00e1s, a poder ser, incluir una llamada a la acci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"858\" height=\"519\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/monday.jpg\" alt=\"landing page Monday\" class=\"wp-image-10548\" title=\"landing page Monday\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/monday.jpg 858w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/monday-300x181.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/monday-768x465.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/monday-705x426.jpg 705w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure>\n\n\n\n<p>En la p\u00e1gina de destino de Monday.com puedes apreciar en su t\u00edtulo el beneficio de utilizar su herramienta y lo refuerza con toda una serie de funcionalidades que se pueden realizar.<\/p>\n\n\n\n<p>Por supuesto debe ser un texto que ofrezca en s\u00ed mismo la <strong>propuesta de valor para el cliente y lo m\u00e1s directo posible, sin rodeos.<\/strong><\/p>\n\n\n\n<p>Si al cliente no lo convencemos de hacer una acci\u00f3n a la primera no te preocupes, para eso tenemos el resto de secciones y elementos de la p\u00e1gina, pero no perdamos la oportunidad desde el principio que llega a nuestra p\u00e1gina.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">CTA o llamada a la acci\u00f3n<\/h3>\n\n\n\n<p>Aunque ya te hemos indicado anteriormente que si es posible el <strong>CTA debe ir incluido en el t\u00edtulo<\/strong>, tambi\u00e9n es normal incluir esta llamada a la acci\u00f3n en otras secciones a lo largo de toda la p\u00e1gina.<\/p>\n\n\n\n<p>El lugar m\u00e1s id\u00f3neo es la parte superior junto al t\u00edtulo pero si nuestra p\u00e1gina tiene mucho contenido podemos incluir <strong>m\u00e1s llamadas a la acci\u00f3n a lo largo de la misma<\/strong>.<\/p>\n\n\n\n<p>Un aspecto importante a tener en cuenta si incluimos varias llamadas a la acci\u00f3n a lo largo de la p\u00e1gina es que todas sean la misma, es decir, que estemos solicitando una misma acci\u00f3n y que adem\u00e1s as\u00ed lo perciba el propio usuario.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1365\" height=\"591\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/endesa.jpg\" alt=\"landing page Endesa\" class=\"wp-image-10549\" title=\"landing page Endesa\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/endesa.jpg 1365w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/endesa-300x130.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/endesa-1030x446.jpg 1030w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/endesa-768x333.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/endesa-705x305.jpg 705w\" sizes=\"(max-width: 1365px) 100vw, 1365px\" \/><\/figure>\n\n\n\n<p>En el caso de esta landing de Endesa la llamada a la acci\u00f3n est\u00e1 enfocada a \u00abcontratar online\u00bb y tal como puedes apreciar al hacer scroll son tres las llamadas a la acci\u00f3n que se pueden llegar a visualizar.<\/p>\n\n\n\n<p>Dos botones de dos tipos de planes a contratar y un formulario que se queda fijo en el lateral a medida que el usuario va haciendo scroll.<\/p>\n\n\n\n<p>De esta manera se ofrece al cliente tres formas de generar un lead (cuatro si contamos la acci\u00f3n solicitar llamada).<\/p>\n\n\n\n<p>El formato m\u00e1s habitual para la llamada a la acci\u00f3n es el <strong>bot\u00f3n<\/strong> y en \u00e9l podemos utilizar s\u00f3lo texto o incluso tambi\u00e9n alg\u00fan icono para dar m\u00e1s dinamismo a la propia acci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"858\" height=\"401\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/netflix.jpg\" alt=\"landing page Netflix\" class=\"wp-image-10550\" title=\"landing page Netflix\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/netflix.jpg 858w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/netflix-300x140.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/netflix-768x359.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/netflix-705x329.jpg 705w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure>\n\n\n\n<p>Netflix utiliza un icono de flecha en sus botones para lograr ese efecto pero adem\u00e1s tambi\u00e9n emplea el <strong>infinitivo<\/strong> en sus textos, muy recomendable utilizar ese tiempo verbal para reforzar esa intenci\u00f3n de aplicar dinamismo.<\/p>\n\n\n\n<p>En cambio si la llamada a la acci\u00f3n incluye la obtenci\u00f3n de un \u00ablead magnet\u00bb (por ejemplo un ebook ) el texto puede ser <strong>redactado en primera persona<\/strong> \u00abQuiero mi ebook\u00bb.<\/p>\n\n\n\n<p>Otro aspecto fundamental es la <strong>elecci\u00f3n del color<\/strong>, nuestra recomendaci\u00f3n es que sea llamativo pero que est\u00e9 bien integrado con la paleta de color de tu web.<\/p>\n\n\n\n<p>Por ejemplo, si tu web tiene una gama de colores tierra neutros tal vez un bot\u00f3n en fucsia muy saturado no sea la mejor idea.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cuerpo<\/h3>\n\n\n\n<p>El cuerpo lo comprenden las secciones en las que desarrollamos toda la informaci\u00f3n que sirve para <strong>ampliar y reforzar nuestro mensaje<\/strong> con la idea de convencer al cliente.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>En buena medida su longitud y cantidad de secciones depende lo complicado que sea vender el producto o servicio para el que queremos obtener el lead.<\/p><\/blockquote>\n\n\n\n<p>Un factor clave al respecto es el precio, esto es muy evidente en las p\u00e1ginas de producto de presentaci\u00f3n de veh\u00edculos, como esta de un Toyota Yaris.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"858\" height=\"405\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/yaris.jpg\" alt=\"landing page Yaris\" class=\"wp-image-10551\" title=\"landing page Yaris\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/yaris.jpg 858w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/yaris-300x142.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/yaris-768x363.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/06\/yaris-705x333.jpg 705w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure>\n\n\n\n<p>A lo largo de del cuerpo puedes incluir:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ventajas de lo que ofreces<\/li><li>Testimonios o reviews de otros clientes para generar m\u00e1s confianza<\/li><li>Comparativas frente a otros productos o marcas para as\u00ed diferenciarte y dar m\u00e1s valor frente al resto a tu propuesta<\/li><li>Caracter\u00edsticas t\u00e9cnicas o informaci\u00f3n m\u00e1s detallada de tu producto o servicio<\/li><li>Preguntas frecuentes que pueda hacerse un cliente para as\u00ed tratar de responder a sus dudas<\/li><\/ul>\n\n\n\n<p>Por \u00faltimo, el orden en el que muestras todas esas secciones es importante.<\/p>\n\n\n\n<p>Debes <strong>conducir al cliente<\/strong> a lo largo de esas secciones para que la lectura tenga un sentido l\u00f3gico y que acabe con una llamada a la acci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Footer o pie de p\u00e1gina<\/h3>\n\n\n\n<p>En el pie p\u00e1gina nuevamente, como en el encabezado, vamos a evitar incluir enlaces que redirijan a otras p\u00e1ginas de tu web, a\u00fan as\u00ed aqu\u00ed es menos relevante que hayan enlaces hacia fuera de tu p\u00e1gina.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Si el posible cliente ha llegado hasta aqu\u00ed haciendo scroll y no se ha decidido a dejarte un lead es que seguramente no lo has convencido.<\/p><\/blockquote>\n\n\n\n<p>A\u00fan as\u00ed mant\u00e9n limpia de elementos esta parte y si necesitas incluir enlaces este es el lugar m\u00e1s indicado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.host-fusion.com\/hosting-wordpress\/\"><img decoding=\"async\" width=\"824\" height=\"243\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/07\/elmejorhostingwordpress.jpg\" alt=\"el mejor hosting wordpress\" class=\"wp-image-10177\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/07\/elmejorhostingwordpress.jpg 824w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/07\/elmejorhostingwordpress-300x88.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/07\/elmejorhostingwordpress-768x226.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/07\/elmejorhostingwordpress-705x208.jpg 705w\" sizes=\"(max-width: 824px) 100vw, 824px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Algunas recomendaciones extra para crear tu Landing Page<\/h2>\n\n\n\n<p>Ya hemos visto la estructura y elementos clave que suelen ser m\u00e1s habituales, ahora en cambio te vamos a dar un breve listado con aspectos que debes tener en cuenta a la hora de dise\u00f1ar tu p\u00e1gina de aterrizaje.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1-Evita los puntos de fuga<\/h3>\n\n\n\n<p>Te lo hemos dicho ya, pero te lo volvemos a recordar, evita incluir cualquier enlace que lleve al usuario fuera de tu p\u00e1gina.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2- Utiliza un estilo visual que el usuario reconozca de inmediato<\/h3>\n\n\n\n<p>Un error habitual es utilizar tipograf\u00edas y colores que nada o poco tienen que ver con los empleados en la marca previamente para enviar al cliente a la p\u00e1gina. Eso puede crear confusi\u00f3n en el posible cliente.<\/p>\n\n\n\n<p>Si por ejemplo hemos captado la visita en un banner de un anuncio en Facebook el dise\u00f1o de este y la p\u00e1gina <strong>deben ser similares<\/strong>.<\/p>\n\n\n\n<p>Respecto a las p\u00e1ginas web corporativas depender\u00e1 de los objetivos, a veces precisamente lo que se persigue es <strong>romper con el dise\u00f1o<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3- Emplea elementos muy visuales<\/h3>\n\n\n\n<p>El empleo de gr\u00e1ficos, iconos, im\u00e1genes y v\u00eddeos hace m\u00e1s atractiva la presentaci\u00f3n de tu contenido.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4- Dedica mucho tiempo a escribir buenos textos<\/h3>\n\n\n\n<p>El <strong>\u00abcopywriting\u00bb<\/strong> es una t\u00e9cnica muy poderosa con la que a trav\u00e9s de tus textos puedes transmitir el mensaje m\u00e1s apropiado para conseguir un lead.<\/p>\n\n\n\n<p>Dedica tiempo a su elaboraci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5- Testea haciendo pruebas A\/B<\/h3>\n\n\n\n<p>Si te es posible crea <strong>distintas versiones de tu landing<\/strong> para valorar qu\u00e9 es lo que mejor funciona para obtener leads.<\/p>\n\n\n\n<p>Lo puedes hacer con peque\u00f1os cambios secci\u00f3n por secci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6- Formulario simple<\/h3>\n\n\n\n<p>Uno de los mayores enemigos para la obtenci\u00f3n de un lead es el formulario.<\/p>\n\n\n\n<p>A medida que se solicitan m\u00e1s datos, m\u00e1s probabilidades existen que el usuario abandone.<\/p>\n\n\n\n<p>En definitiva, <strong>pide s\u00f3lo los datos que necesites y sean imprescindibles<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">7- Dise\u00f1o para m\u00f3vil<\/h3>\n\n\n\n<p>La mayor\u00eda de tus posibles clientes van a acceder desde un dispositivo m\u00f3vil, dise\u00f1a tu landing para ese tama\u00f1o de pantallas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">8- SEO y SEM, tus aliados<\/h3>\n\n\n\n<p>Tu p\u00e1gina puede estar genialmente dise\u00f1ada para lograr leads pero como no reciba visitas ser\u00e1 un fracaso.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Tambi\u00e9n te puede interesar: <a href=\"https:\/\/www.host-fusion.com\/blog\/2021\/01\/26\/tendencias-seo\/\">Tendencias SEO<\/a><\/em><\/p><\/blockquote>\n\n\n\n<p>Invierte recursos en mejorar su posicionamiento org\u00e1nico o el pagado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusiones<\/h2>\n\n\n\n<p>Dise\u00f1ar una p\u00e1gina de aterrizaje que convierta no es complicado si tenemos en cuenta los elementos y aspectos que hemos visto, pero tambi\u00e9n en gran medida depender\u00e1 del tipo de objetivo que tengamos entre manos y c\u00f3mo nos hayamos planteado llevar tr\u00e1fico.<\/p>\n\n\n\n<p>En ese sentido una estrategia completa y bien definida es clave.<\/p>\n\n\n\n<p>Por otro lado, una landing es una p\u00e1gina viva que incluso una vez publicada podemos seguir optimizando y mejorando con el fin de aumentar las conversiones.<\/p>\n\n\n\n<p><strong>Esperamos haberte ayudado a comprender mejor qu\u00e9 es una landing page y c\u00f3mo debes dise\u00f1ar la tuya.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una landing page sigue siendo una estupenda herramienta que ofrece toda una serie de posibilidades extra a cualquier proyecto web. Entre todas las estrategias de marketing digital, el dise\u00f1o de una landing page es una opci\u00f3n muy interesante, y una buena herramienta que sirve para llevar adelante acciones que se pueden complementar a su vez [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,567,751,369,91,1410],"tags":[1456,496,1454],"class_list":["post-10543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alojamiento-web","category-hosting-2","category-hosting-wordpress-2","category-marketing-online","category-posicionamiento-web","category-seo","tag-crear-landing-page","tag-landing-page","tag-que-es-una-landing-page"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/posts\/10543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/comments?post=10543"}],"version-history":[{"count":0,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/posts\/10543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/media\/10545"}],"wp:attachment":[{"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/media?parent=10543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/categories?post=10543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/tags?post=10543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}