{"id":10401,"date":"2021-02-24T10:00:00","date_gmt":"2021-02-24T09:00:00","guid":{"rendered":"https:\/\/www.host-fusion.com\/blog\/?p=10401"},"modified":"2021-02-23T12:31:26","modified_gmt":"2021-02-23T11:31:26","slug":"seo-local-google-my-business","status":"publish","type":"post","link":"https:\/\/www.host-fusion.com\/blog\/2021\/02\/24\/seo-local-google-my-business\/","title":{"rendered":"Mejora el SEO Local con Google My Business"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"824\" height=\"243\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/seo_local_google_my_business.jpg\" alt=\"Mejora el SEO Local con Google My Business\" class=\"wp-image-10420\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/seo_local_google_my_business.jpg 824w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/seo_local_google_my_business-300x88.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/seo_local_google_my_business-768x226.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/seo_local_google_my_business-705x208.jpg 705w\" sizes=\"(max-width: 824px) 100vw, 824px\" \/><\/figure>\n\n\n\n<p>Desde hace un tiempo una de las mejores formas de posicionar de modo org\u00e1nico un negocio f\u00edsico es la <strong>combinaci\u00f3n de SEO Local y Google My Business<\/strong>.<\/p>\n\n\n\n<p>En realidad la herramienta de Google no es m\u00e1s que una parte m\u00e1s del SEO Local pero desde luego cada vez cobra m\u00e1s importancia, hasta tal punto que utiliz\u00e1ndola bien obtendr\u00e1s resultados m\u00e1s que evidentes a nivel de posicionamiento local.<\/p>\n\n\n\n<p>Pero, \u00bfqu\u00e9 es lo m\u00e1s importante y necesario que optimizar en Google My Business para <strong>posicionar mejor tu negocio<\/strong>?<\/p>\n\n\n\n<p>Si tienes o gestionas la comunicaci\u00f3n, marketing o visibilidad de un negocio local en internet este post te va a interesar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es el SEO Local?<\/h2>\n\n\n\n<p>El SEO Local o posicionamiento local son todas aquellas <strong>acciones que desempe\u00f1amos para posicionar la actividad de un negocio para una determinada ubicaci\u00f3n f\u00edsica o zona geogr\u00e1fica.<\/strong><\/p>\n\n\n\n<p>As\u00ed pues, se trata de que una empresa o negocio se posicione para determinadas intenciones de b\u00fasqueda que hagan los usuarios que est\u00e9n vinculados con una localizaci\u00f3n geogr\u00e1fica.<\/p>\n\n\n\n<p>Esas intenciones de b\u00fasqueda pueden estar relacionadas con la venta de productos y servicios, ya sea <strong>f\u00edsicamente en el propio local o bien en toda una zona geogr\u00e1fica<\/strong>.<\/p>\n\n\n\n<p>Adem\u00e1s el SEO Local afecta tambi\u00e9n a la visibilidad org\u00e1nica que obtiene nuestro negocio por otras v\u00edas distintas al SEO tradicional, algo que Google viene a llamar <em>Local Pack<\/em> en sus SERPS.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"858\" height=\"371\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/hostfusion-maps.jpg\" alt=\"SEO Local\" class=\"wp-image-10405\" title=\"SEO Local\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/hostfusion-maps.jpg 858w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/hostfusion-maps-300x130.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/hostfusion-maps-768x332.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/hostfusion-maps-705x305.jpg 705w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure>\n\n\n\n<p>Seguro que puedes identificar claramente qu\u00e9 es una b\u00fasqueda local y c\u00f3mo se visualiza en Google Maps o las fichas de ubicaciones mostradas en el buscador \u00bfverdad?<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ten en cuenta que ya el 46% de las b\u00fasquedas est\u00e1n vinculadas a las b\u00fasquedas locales en Google<\/p><\/blockquote>\n\n\n\n<p>O lo que es lo mismo, los negocios que no est\u00e1n optimizados para el SEO Local est\u00e1n perdiendo un 46% de todas las b\u00fasquedas que se est\u00e1n haciendo en Google. Y lo que es peor, la tendencia es que cada vez sean m\u00e1s las b\u00fasquedas locales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default\"><a href=\"https:\/\/www.host-fusion.com\/redes-sociales\/\"><img decoding=\"async\" width=\"824\" height=\"243\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/01\/25_descuento.jpg\" alt=\"25% dto para siempre en Hosting WordPress\" class=\"wp-image-10372\" title=\"25% dto para siempre en Hosting WordPress\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/01\/25_descuento.jpg 824w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/01\/25_descuento-300x88.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/01\/25_descuento-768x226.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/01\/25_descuento-705x208.jpg 705w\" sizes=\"(max-width: 824px) 100vw, 824px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ahora bien, \u00bfqu\u00e9 factores tiene en cuenta Google para posicionar un negocio local para determinadas intenciones de b\u00fasqueda?<\/h3>\n\n\n\n<p>Son tres los factores m\u00e1s importantes que tiene en cuenta:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Popularidad:<\/strong> Un lugar que dispone de mejores opiniones o una mayor cantidad de visitas f\u00edsicas aunque se puede encontrar a mayor distancia obtiene un mejor posicionamiento.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Proximidad:<\/strong> Google tiene en cuenta el lugar desde el que hacemos la b\u00fasqueda o la localizaci\u00f3n con la que est\u00e1 vinculada nuestra b\u00fasqueda. A veces incluso simplemente lo interpreta de nuestra propia consulta. Prioriza por tanto los negocios que est\u00e9n m\u00e1s pr\u00f3ximos a estas dos variables.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Relevancia:<\/strong> Aquellos negocios que mejor satisfacen una intenci\u00f3n de b\u00fasqueda tienen prioridad para ser mostrados. Por tanto, entre dos negocios que ofrecen servicios similares tiene prioridad el que mejor atiende a esa intenci\u00f3n de b\u00fasqueda, independientemente de que se puede encontrar m\u00e1s lejos. <\/li><\/ul>\n\n\n\n<p>Y ahora quiz\u00e1s te est\u00e9s preguntando, \u00bfc\u00f3mo analiza Google todos esos datos? <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Tambi\u00e9n te puede interesar: <a href=\"https:\/\/www.host-fusion.com\/blog\/2021\/01\/26\/tendencias-seo\/\" title=\"Tendencias SEO\">Tendencias SEO<\/a><\/em> <\/p><\/blockquote>\n\n\n\n<p>Ah\u00ed es donde entra en juego la aplicaci\u00f3n de Google My Business, es la herramienta (no la \u00fanica) que mejor le sirve a Google para obtener informaci\u00f3n de cada negocio que le proporcionan los propietarios y los clientes. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sin embargo SEO Local no es s\u00f3lo Google My Business <\/h2>\n\n\n\n<p>Por supuesto hay otra serie de <strong>acciones que influyen en un mejor posicionamiento<\/strong> y que no est\u00e1n directamente vinculadas con GMB. Algunas de estas acciones son las siguientes:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Incluir informaci\u00f3n en<strong>perfiles online<\/strong>: Adem\u00e1s de GMB, Yelp, Facebook, TripAdvisor<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Crear <strong>contenido en tu blog<\/strong>: publicaciones de posts enfocadas en contenidos locales y establecimiento de una buena estrategia de enlazado en estos contenidos<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Obtenci\u00f3n de <strong>comentarios, recomendaciones y opiniones<\/strong> de tus servicios o productos<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Incluir informaci\u00f3n de tu negocio en <strong>directorios locales<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Establecer un <a href=\"https:\/\/support.google.com\/webmasters\/answer\/3069489?hl=es\" target=\"_blank\" rel=\"noreferrer noopener nofollow\" title=\"marcado de datos Schema\">marcado de datos Schema<\/a> en tu web correcto<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Optimizar tu web<\/strong> para todo tipo de dispositivos, especialmente m\u00f3viles<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Mejorar la <strong>autoridad de tu dominio<\/strong> <\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">SEO Local en Google My Business, \u00bfpor d\u00f3nde empezar?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" width=\"858\" height=\"503\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/seo_local_google-my-business.jpg\" alt=\"Seo Local Google My Business\" class=\"wp-image-10407\" title=\"Seo Local Google My Business\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/seo_local_google-my-business.jpg 858w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/seo_local_google-my-business-300x176.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/seo_local_google-my-business-768x450.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/seo_local_google-my-business-705x413.jpg 705w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.google.com\/intl\/es_es\/business\/\" rel=\"noreferrer noopener nofollow\" target=\"_blank\" title=\"Google My Business\">Google My Business<\/a> es la gran herramienta por la que apuesta la gran G para conectar negocios, empresas y clientes para dotar de m\u00e1s datos que aportar a su negocio y fuente de ingresos principal a\u00fan: <\/p>\n\n\n\n<p><strong>La publicidad<\/strong>. En esta herramienta confluyen y se integran funcionalidades de redes sociales, de b\u00fasqueda, geoposicionamiento, etc. Para comenzar en Google My Business lo primero de todo que debes hacer es <strong>dar de alta tu negocio<\/strong>. Para ello debes de disponer de una cuenta de Gmail y comprobar antes de nada si tu negocio ya est\u00e1 en Google Maps, en ese caso lo puedes reclamar como propio, si no puedes darlo de alta desde cero. En cualquiera de los dos casos deber\u00e1s <strong>verificar tu ubicaci\u00f3n<\/strong>, por tel\u00e9fono o por correo postal<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Verifique su empresa en google\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/feZUWLujvK0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p>Una vez dada de alta tu ubicaci\u00f3n puedes ir completando paso a paso cada una de las secciones de las que dispone esta herramienta para tu negocio.<\/p>\n\n\n\n<p>Nuestra recomendaci\u00f3n es que completes con la mayor informaci\u00f3n posible todas las secciones.<\/p>\n\n\n\n<p>M\u00e1s adelante te contamos las secciones que son m\u00e1s importantes para una correcta optimizaci\u00f3n, pero ten en cuenta que cuanta m\u00e1s informaci\u00f3n proporcionamos de nuestro negocio, m\u00e1s facilidades le estamos dando a Google para que lo conozca mejor y, por tanto, m\u00e1s posibilidades que lo muestre en m\u00e1s b\u00fasquedas.<\/p>\n\n\n\n<p>Adem\u00e1s, GMB nos lo pone f\u00e1cil indicando el porcentaje en que hemos completado nuestro perfil de empresa.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"634\" height=\"213\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/completar-perfil.jpg\" alt=\"Completar perfil de empresa en Google my business\" class=\"wp-image-10410\" title=\"Completar perfil de empresa en Google my business\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/completar-perfil.jpg 634w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/completar-perfil-300x101.jpg 300w\" sizes=\"(max-width: 634px) 100vw, 634px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Beneficios de disponer de una ubicaci\u00f3n de Google My Business para nuestro negocio<\/h2>\n\n\n\n<p>Entre los principales beneficios se encuentran los siguientes:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Una herramienta de contacto directo con tus clientes<\/h3>\n\n\n\n<p>Obt\u00e9n una comunicaci\u00f3n directa y fluida con tus clientes que puede repercutir por ejemplo en ofrecer mejores servicios o una mejor atenci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Te permite conseguir m\u00e1s clientes<\/h3>\n\n\n\n<p>Ten acceso a m\u00e1s clientes ganando m\u00e1s visibilidad, cu\u00e9ntales qu\u00e9 es lo que ofreces, qu\u00e9 hace tu empresa. Consigue como consecuencia m\u00e1s ventas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Es gratis<\/h3>\n\n\n\n<p>Utilizar todas las funcionalidades de GMB no tiene coste para tu negocio.<\/p>\n\n\n\n<p>Sin duda esta es la gran baza de momento de esta herramienta, sobre todo si el presupuesto para acciones de marketing y publicidad de tu negocio es ajustado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Es la herramienta que m\u00e1s influye en el SEO Local para posicionar en Google<\/h3>\n\n\n\n<p>Tanto es as\u00ed que tu negocio puede prescindir de web y otras acciones que mencion\u00e1bamos anteriormente y posicionarse en las SERPS para resultados locales \u00fanicamente con una ubicaci\u00f3n bien optimizada.<\/p>\n\n\n\n<p>Adem\u00e1s, hay negocios que por su propia actividad les puede ser m\u00e1s que suficiente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aspectos clave a optimizar en Google My Business<\/h2>\n\n\n\n<p>Bien, como te dec\u00edamos anteriormente vamos a indicarte aquello a lo que debes prestar m\u00e1s atenci\u00f3n a la hora de optimizar y gestionar tu ubicaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">NAP<\/h3>\n\n\n\n<p>El NAP hace referencia a las iniciales en ingl\u00e9s de <strong>nombre, direcci\u00f3n y tel\u00e9fono<\/strong>.<\/p>\n\n\n\n<p>Este es un aspecto clave de la informaci\u00f3n que facilitamos y que en numerosas ocasiones no se tiene en cuenta.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"617\" height=\"230\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/nap.jpg\" alt=\"NAP Google my business\" class=\"wp-image-10412\" title=\"NAP Google my business\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/nap.jpg 617w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/nap-300x112.jpg 300w\" sizes=\"(max-width: 617px) 100vw, 617px\" \/><\/figure><\/div>\n\n\n\n<p>La concordancia entre esos tres datos que facilitamos en nuestra ficha de GMB y los datos que ofrecemos en nuestra web (en el footer o p\u00e1gina de contacto) debe ser id\u00e9ntica. Adem\u00e1s tambi\u00e9n debemos hacer que coincida en otros sitios como pueden ser redes sociales directorios locales.<\/p>\n\n\n\n<p><strong>El NAP debe tener consistencia en todos los lugares en que se muestre<\/strong>, de tal modo que Google identifique claramente que se refieren a un mismo negocio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La importancia de las rese\u00f1as<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"858\" height=\"238\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/resenas_gmb.jpg\" alt=\"Rese\u00f1as en Google\" class=\"wp-image-10415\" title=\"Rese\u00f1as en Google\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/resenas_gmb.jpg 858w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/resenas_gmb-300x83.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/resenas_gmb-768x213.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/resenas_gmb-705x196.jpg 705w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure><\/div>\n\n\n\n<p>Las rese\u00f1as son otro de los aspectos clave para mejorar tu posicionamiento.<\/p>\n\n\n\n<p>Diversos estudios afirman que un amplio porcentaje de las <strong>decisiones de compra<\/strong> de los clientes se basan en las rese\u00f1as que leemos acerca de un negocio.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00bfQui\u00e9n no ha mirado alguna vez las rese\u00f1as de un restaurante antes de reservar mesa?<\/p><\/blockquote>\n\n\n\n<p>Por supuesto Google es consciente del valor que les otorgan los clientes y quiz\u00e1s por ello las tiene muy en cuenta para posicionar un negocio.<\/p>\n\n\n\n<p>Por contra de lo que muchas personas creen <strong>no influye tanto el n\u00famero de rese\u00f1as como la puntuaci\u00f3n-valoraci\u00f3n que se obtiene<\/strong>.<\/p>\n\n\n\n<p>Esto es lo que m\u00e1s influye:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>Puntuaci\u00f3n-valoraci\u00f3n<\/strong> que nos dan los clientes. Trata de evitar recibir puntuaciones bajas en la medida de lo posible.<\/li><li><strong>Extensi\u00f3n, optimizaci\u00f3n y valor de la rese\u00f1a<\/strong>. Una rese\u00f1a positiva con m\u00e1s de 200 caracteres, incluyendo una imagen y alguna <em>Keyword<\/em> relacionada con nuestros servicios o productos por los que queremos posicionar es \u00f3ptima. En definitiva, que aporte valor a otro cliente que la lea.<\/li><li><strong>N\u00famero de rese\u00f1as<\/strong>. Por supuesto es mejor tener 20 rese\u00f1as \u00f3ptimas que s\u00f3lo 5, pero tambi\u00e9n mejor tener 5 \u00f3ptimas que 20 de poco valor e incluso alguna con puntuaci\u00f3n baja.<\/li><\/ol>\n\n\n\n<p>Ahora bien, \u00a1las rese\u00f1as no te van a llegar solas!<\/p>\n\n\n\n<p>Tienes que poner todos los medios a tu alcance para facilitar a tus clientes que las hagan.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"759\" height=\"724\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/resenas_google_my_business.jpg\" alt=\"Rese\u00f1as Google My Business Host-Fusion\" class=\"wp-image-10414\" title=\"Rese\u00f1as Google My Business Host-Fusion\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/resenas_google_my_business.jpg 759w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/resenas_google_my_business-300x286.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/resenas_google_my_business-705x672.jpg 705w\" sizes=\"(max-width: 759px) 100vw, 759px\" \/><\/figure><\/div>\n\n\n\n<p>Google en el apartado \u00abRecibe m\u00e1s rese\u00f1as\u00bb nos facilita un <strong>generador de enlace a tus rese\u00f1as<\/strong> para que as\u00ed tus clientes puedan directamente hacer clic y dejarte su rese\u00f1a.<\/p>\n\n\n\n<p>Te dejamos aqu\u00ed el nuestro para que si te animas nos dejes una rese\u00f1a positiva:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Nuestras <a href=\"https:\/\/g.page\/HostFusion\/review\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"Rese\u00f1as en Google My Business\">Rese\u00f1as en Google My Business<\/a><\/p><\/blockquote>\n\n\n\n<p>Algunas ideas que te sugerimos para conseguir que tus clientes te dejen rese\u00f1as:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Incluir enlace en un <strong>email<\/strong> autom\u00e1tico tras hacer una compra<\/li><li>Organizar <strong>sorteos<\/strong> de alg\u00fan producto e incluir en las bases dejar una rese\u00f1a positiva de tu negocio (cuidado con esto o se te puede volver en contra)<\/li><li>Incluye un mensaje en los <strong>tickets o tarjetas de vista<\/strong> invitando a hacer un rese\u00f1a (por ejemplo en el caso de un restaurante o un hotel)<\/li><\/ul>\n\n\n\n<p>Por \u00faltimo, responde siempre a todas las rese\u00f1as, en especial a las que no sean positivas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Te puede interesar <a href=\"https:\/\/www.host-fusion.com\/blog\/2020\/06\/10\/como-mostrar-las-resenas-de-google-my-business-en-wordpress\/\" title=\"C\u00f3mo mostrar las rese\u00f1as de Google my Business en WordPress\">C\u00f3mo mostrar las rese\u00f1as de Google my Business en WordPress<\/a><\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">SEO en los campos de categor\u00edas, descripci\u00f3n, productos y servicios<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"858\" height=\"257\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/descripcion_google_my_business.jpg\" alt=\"Descripci\u00f3n Host-Fusion en Google My Business\" class=\"wp-image-10416\" title=\"Descripci\u00f3n Host-Fusion en Google My Business\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/descripcion_google_my_business.jpg 858w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/descripcion_google_my_business-300x90.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/descripcion_google_my_business-768x230.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/descripcion_google_my_business-705x211.jpg 705w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure><\/div>\n\n\n\n<p>\u00bfSab\u00edas que podemos hacer SEO On Page con <em>Keywords<\/em> tal como hacemos en una web?<\/p>\n\n\n\n<p>Bueno, no es exactamente igual pero bastante parecido, y nada complicado de llevar a cabo.<\/p>\n\n\n\n<p>En los campos de categor\u00edas, descripci\u00f3n, servicios y productos debemos incluir las <strong>palabras clave por las que queremos posicionar nuestro negocio<\/strong>.<\/p>\n\n\n\n<p>Tal como hacemos en una web definimos unas <em>Keywords<\/em> principales que vamos a utilizar en categor\u00edas de nuestro negocio y la descripci\u00f3n del mismo.<\/p>\n\n\n\n<p>Por otro lado unas <em>keywords<\/em> secundarias (que pueden coincidir con las utilizadas en la descripci\u00f3n) utilizadas en los productos y servicios que tu empresa o negocio ofrece.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Im\u00e1genes que hacen SEO Local<\/h3>\n\n\n\n<p>Las im\u00e1genes son otro tipo de contenido que cada vez cobra m\u00e1s relevancia para posicionar en las SERPS.<\/p>\n\n\n\n<p>Las fotos que se pueden mostrar de tu negocio pueden ser subidas tanto por clientes como por ti mismo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong><em>Tambi\u00e9n te puede interesar: <a href=\"https:\/\/www.host-fusion.com\/blog\/2020\/01\/07\/cuales-son-los-tamanos-de-las-imagenes-en-redes-sociales-en-2020\/\" title=\"\u00bfCu\u00e1les son los tama\u00f1os de las im\u00e1genes en redes sociales en 2021?\">\u00bfCu\u00e1les son los tama\u00f1os de las im\u00e1genes en redes sociales en 2021?<\/a><\/em><\/strong><\/p><\/blockquote>\n\n\n\n<p>Es interesante que tus clientes (como dec\u00edamos anteriormente) junto a la rese\u00f1a compartan una imagen tuya, sin embargo es mejor que te encargues de subir la mayor\u00eda de fotos t\u00fa por varios motivos que son beneficiosos para ti:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tus fotograf\u00edas son probablemente de <strong>mejor calidad<\/strong>. No hace falta que contrates a un fot\u00f3grafo (aunque es recomendable) pero toma fotos de la mejor calidad posible.<\/li><li><strong>Puedes georreferenciar<\/strong> (o geolocalizar) tus im\u00e1genes, es decir a\u00f1adir en los metadatos la localizaci\u00f3n de tu negocio.<\/li><li>Incluir\u00e1s las <strong>palabras clave<\/strong> principales y secundarias para tu negocio en el nombre del archivo que subas. Por ejemplo, si subes una foto de un entrante del menu de tu restaurante haz que ese archivo contenga el nombre del plato.<\/li><\/ul>\n\n\n\n<p>Por supuesto, cu\u00e1ntas m\u00e1s fotos, y de calidad subas, mejor.<\/p>\n\n\n\n<p>Ah, y estas recomendaciones tambi\u00e9n son para v\u00eddeos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Publicaciones para ganar visibilidad<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"858\" height=\"753\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/publicaciones.jpg\" alt=\"Publicaciones en Google my Business\" class=\"wp-image-10417\" title=\"Publicaciones en Google my Business\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/publicaciones.jpg 858w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/publicaciones-300x263.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/publicaciones-768x674.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2021\/02\/publicaciones-705x619.jpg 705w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure><\/div>\n\n\n\n<p>Google valora mucho que generemos contenido de forma frecuente y peri\u00f3dica mostrando nuestras publicaciones de forma destacada en las SERPS.<\/p>\n\n\n\n<p>Aprovecha esta visibilidad que nos ofrece GMB para <strong>ganar en visibilidad<\/strong> y obtener algunas ventajas extra muy interesantes como:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Vender productos<\/li><li>Lanzar ofertas<\/li><li>Generar tr\u00e1fico a tu web<\/li><\/ul>\n\n\n\n<p>Pero sobre todo, utiliza las publicaciones para aportar contenido sobre tu negocio, tus productos y lo que puedes ofrecer a tus clientes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusiones<\/h2>\n\n\n\n<p>Como hemos visto a lo largo de este post hay razones de peso por las que si tienes un negocio local no s\u00f3lo debes tener una ubicaci\u00f3n sino adem\u00e1s perfectamente optimizada.<\/p>\n\n\n\n<p>Son muchas las ventajas que puede reportar a tu negocio llevar a cabo una optimizaci\u00f3n de SEO Local con Google My Business y como ves sin necesidad de invertir en campa\u00f1as de publicidad.<\/p>\n\n\n\n<p><strong>\u00bfTe animas a optimizar ya la ficha de tu negocio?<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/www.host-fusion.com\/hosting-para-woocommerce\/\"><img decoding=\"async\" width=\"824\" height=\"243\" src=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/02\/elmejorhostingwoocommerce-1.jpg\" alt=\"El mejor Hosting para WooCommerce\" class=\"wp-image-9796\" srcset=\"https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/02\/elmejorhostingwoocommerce-1.jpg 824w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/02\/elmejorhostingwoocommerce-1-300x88.jpg 300w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/02\/elmejorhostingwoocommerce-1-768x226.jpg 768w, https:\/\/www.host-fusion.com\/blog\/wp-content\/uploads\/2020\/02\/elmejorhostingwoocommerce-1-705x208.jpg 705w\" sizes=\"(max-width: 824px) 100vw, 824px\" \/><\/a><figcaption>Hosting WooCommerce<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Desde hace un tiempo una de las mejores formas de posicionar de modo org\u00e1nico un negocio f\u00edsico es la combinaci\u00f3n de SEO Local y Google My Business. En realidad la herramienta de Google no es m\u00e1s que una parte m\u00e1s del SEO Local pero desde luego cada vez cobra m\u00e1s importancia, hasta tal punto que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10420,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47,567,751,369,91,1410],"tags":[1446,1447],"class_list":["post-10401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-google","category-hosting-2","category-hosting-wordpress-2","category-marketing-online","category-posicionamiento-web","category-seo","tag-google-my-business","tag-seo-local"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/posts\/10401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/comments?post=10401"}],"version-history":[{"count":0,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/posts\/10401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/media\/10420"}],"wp:attachment":[{"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/media?parent=10401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/categories?post=10401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.host-fusion.com\/blog\/wp-json\/wp\/v2\/tags?post=10401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}